{"id":29,"count":10,"description":"trading academy signals, forex, indices, commodities","link":"https:\/\/tradingacademysignals.com\/pt\/categoria-produto\/trading-plans\/","name":"Trading plans","slug":"trading-plans","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/tradingacademysignals.com\/pt\/wp-json\/wp\/v2\/product_cat\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tradingacademysignals.com\/pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/tradingacademysignals.com\/pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/tradingacademysignals.com\/pt\/wp-json\/wp\/v2\/product?product_cat=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}