{"id":39,"count":253,"description":"Weekly reports","link":"https:\/\/tradingacademysignals.com\/ro\/category\/weekly-reports\/","name":"Reports","slug":"weekly-reports","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/tradingacademysignals.com\/ro\/wp-json\/wp\/v2\/categories\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tradingacademysignals.com\/ro\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/tradingacademysignals.com\/ro\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/tradingacademysignals.com\/ro\/wp-json\/wp\/v2\/posts?categories=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}